{"id":3309,"date":"2023-07-24T12:51:40","date_gmt":"2023-07-24T12:51:40","guid":{"rendered":"https:\/\/www.lafiracentrecomercial.com\/?p=3309"},"modified":"2024-01-19T12:41:42","modified_gmt":"2024-01-19T12:41:42","slug":"la-fira-centre-comercial-regala-entrades-de-cinema-per-el-dia-dels-avis","status":"publish","type":"post","link":"https:\/\/www.lafiracentrecomercial.com\/ca\/la-fira-centre-comercial-regala-entrades-de-cinema-per-el-dia-dels-avis\/","title":{"rendered":"La Fira Centre Comercial regala entrades de cinema per el &#8216;Dia dels Avis&#8217;"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><\/h5>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Fira Centre Comercial celebra la &#8216;setmana dels avis&#8217; amb diferents accions i reivindica la import\u00e0ncia dels m\u00e9s grans en l&#8217;oci familiar<\/p>\n","protected":false},"author":2,"featured_media":3487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-3309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"featured_img_url":"https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/Noticia-Abuelos.webp","custom_meta":{"contentDirectorios":"","contentAux":"<div data-id=\"3309\" class=\"mfn-builder-content mfn-default-content-buider\"><section class=\"section mcb-section mfn-default-section mcb-section-zya15xmm4\"   style=\"\" ><div class=\"mcb-background-overlay\"><\/div><div class=\"section_wrapper mfn-wrapper-for-wraps mcb-section-inner mcb-section-inner-zya15xmm4\"><div  class=\"wrap mcb-wrap mcb-wrap-57fgysmgw one tablet-one laptop-one mobile-one vb-item clearfix\" data-desktop-col=\"one\" data-laptop-col=\"laptop-one\" data-tablet-col=\"tablet-one\" data-mobile-col=\"mobile-one\" style=\"\"   ><div class=\"mcb-wrap-inner mcb-wrap-inner-57fgysmgw mfn-module-wrapper mfn-wrapper-for-wraps\"  ><div class=\"mcb-wrap-background-overlay\"><\/div><div  class=\"column mcb-column mcb-item-b93pzwxr one laptop-one tablet-one mobile-one column_heading vb-item\" style=\"\" ><div class=\"mcb-column-inner mfn-module-wrapper mcb-column-inner-b93pzwxr mcb-item-heading-inner\"><h1 class=\"title\">La Fira Centre Comercial regala entrades de cinema per el 'Dia dels Avis'<\/h1><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"section mcb-section mfn-default-section mcb-section-o0da3g8i\"   style=\"\" ><div class=\"mcb-background-overlay\"><\/div><div class=\"section_wrapper mfn-wrapper-for-wraps mcb-section-inner mcb-section-inner-o0da3g8i\"><div  class=\"wrap mcb-wrap mcb-wrap-mr9i86wt one tablet-one laptop-one mobile-one vb-item clearfix\" data-desktop-col=\"one\" data-laptop-col=\"laptop-one\" data-tablet-col=\"tablet-one\" data-mobile-col=\"mobile-one\" style=\"\"   ><div class=\"mcb-wrap-inner mcb-wrap-inner-mr9i86wt mfn-module-wrapper mfn-wrapper-for-wraps\"  ><div class=\"mcb-wrap-background-overlay\"><\/div><div  class=\"column mcb-column mcb-item-j55y5t58 one laptop-one tablet-one mobile-one column_column vb-item\" style=\"\" ><div class=\"mcb-column-inner mfn-module-wrapper mcb-column-inner-j55y5t58 mcb-item-column-inner\"><div class=\"column_attr mfn-inline-editor clearfix\" style=\"\"><ul>\n<li>\n<h4>La Fira Centre Comercial celebra la 'setmana dels avis' amb diferents accions i reivindica la import\u00e0ncia dels m\u00e9s grans en l'oci familiar.<\/h4>\n<\/li>\n<\/ul><\/div><\/div><\/div><div  class=\"column mcb-column mcb-item-f042ryf2c one laptop-one tablet-one mobile-one column_image vb-item\" style=\"\" ><div class=\"mcb-column-inner mfn-module-wrapper mcb-column-inner-f042ryf2c mcb-item-image-inner\"><div class=\"image_frame image_item no_link scale-with-grid element_classes alignnone no_border mfn-img-box\" ><div class=\"image_wrapper\"><img width=\"1920\" height=\"1280\" src=\"https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia.webp\" class=\"scale-with-grid\" alt=\"Abuelos y nietos\" style=\"\" decoding=\"async\" srcset=\"https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia.webp 1920w, https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia-500x333.webp 500w, https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia-1200x800.webp 1200w, https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia-300x200.webp 300w, https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia-768x512.webp 768w, https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia-1536x1024.webp 1536w, https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia-113x75.webp 113w, https:\/\/www.lafiracentrecomercial.com\/wp-content\/uploads\/2023\/08\/JCBC9308S-copia-480x320.webp 480w\" sizes=\"(max-width:767px) 480px, (max-width:1920px) 100vw, 1920px\" \/><\/div><\/div>\n<\/div><\/div><div  class=\"column mcb-column mcb-item-df00nk6lj one laptop-one tablet-one mobile-one column_column vb-item\" style=\"\" ><div class=\"mcb-column-inner mfn-module-wrapper mcb-column-inner-df00nk6lj mcb-item-column-inner\"><div class=\"column_attr mfn-inline-editor clearfix\" style=\"\"><p><strong>Reus, juliol 2023.<\/strong><\/p>\n<p>La Fira Centre Comercial ha preparat una s\u00e8rie d'accions entorn del \u2018Dia Mundial dels Avis\u2019 que se celebra el 26 de juliol. Durant tota la setmana es faran sortejos de plans d'oci a trav\u00e9s de xarxes socials, i el dia central de la celebraci\u00f3, el 26 de juliol, es regalar\u00e0 una entrada doble de cinema a tot n\u00e9t que es presenti amb el seu avi o \u00e0via al punt d'atenci\u00f3 al client del centre comercial (amb un m\u00e0xim de 50 entrades dobles).<\/p>\n<p>Per a La Fira Centre Comercial aquesta acci\u00f3 \u00e9s \"una aposta per l'oci inclusiu que busca ressaltar la import\u00e0ncia de l'oci de valor i reivindicar la figura dels avis en l'entorn familiar.\"<\/p>\n<p>A m\u00e9s, i per complementar totes les accions dedicades als m\u00e9s s\u00e8niors, els Cinemes Axion de La Fira s'adhereixen al programa del govern d'ajudes al cinema, de manera que cada dimarts els majors de 65 anys podran anar al cinema per tan sols 2 euros. Aquesta iniciativa se suma al Cicle de Cinema Infantil en Catal\u00e0 que el Centre Comercial ofereix cada any durant els mesos de juliol i agost amb pel\u00b7l\u00edcules infantils tradu\u00efdes al catal\u00e0 i entrada a preu redu\u00eft, amb suport del CNL(Consorci Nacional per la Llengua)\u00a0i la conselleria de cultura de l'Ajuntament de Reus.<\/p>\n<p>Amb aquestes accions La Fira, Centre Comercial gestionat per SILICIUS, la SOCIMI del Grup Mazabi\u00a0especialitzada en la compra i gesti\u00f3 d'actius, mant\u00e9 la seva aposta per oferir experi\u00e8ncies per a tots i totes.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"section mcb-section mfn-default-section mcb-section-og5fq3h4p\"   style=\"\" ><div class=\"mcb-background-overlay\"><\/div><div class=\"section_wrapper mfn-wrapper-for-wraps mcb-section-inner mcb-section-inner-og5fq3h4p\"><div  class=\"wrap mcb-wrap mcb-wrap-gf66ay6dq one tablet-one laptop-one mobile-one vb-item clearfix\" data-desktop-col=\"one\" data-laptop-col=\"laptop-one\" data-tablet-col=\"tablet-one\" data-mobile-col=\"mobile-one\" style=\"\"   ><div class=\"mcb-wrap-inner mcb-wrap-inner-gf66ay6dq mfn-module-wrapper mfn-wrapper-for-wraps\"  ><div class=\"mcb-wrap-background-overlay\"><\/div><div  class=\"column mcb-column mcb-item-7x4f9fqu one laptop-one tablet-one mobile-one column_button vb-item\" style=\"\" ><div class=\"mcb-column-inner mfn-module-wrapper mcb-column-inner-7x4f9fqu mcb-item-button-inner\"><a class=\"button  button_left button_size_1\" href=\"https:\/\/www.lafiracentrecomercial.com\/ca\/actualitat-sin-filtros\/\"         title=\"\"><span class=\"button_icon\"><i class=\"icon-left-open\"  aria-hidden=\"true\"><\/i><\/span><span class=\"button_label\">Tornar a Actualitat<\/span><\/a>\n<\/div><\/div><\/div><\/div><\/div><\/section><\/div>"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/posts\/3309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/comments?post=3309"}],"version-history":[{"count":7,"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/posts\/3309\/revisions"}],"predecessor-version":[{"id":4493,"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/posts\/3309\/revisions\/4493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/media\/3487"}],"wp:attachment":[{"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/media?parent=3309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/categories?post=3309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lafiracentrecomercial.com\/ca\/wp-json\/wp\/v2\/tags?post=3309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}